{"id":1136,"count":0,"description":"","link":"https:\/\/stakeup.be\/nl\/category\/gidsen-voor-beginners\/","name":"Gidsen voor beginners","slug":"gidsen-voor-beginners","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/stakeup.be\/nl\/wp-json\/wp\/v2\/categories\/1136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stakeup.be\/nl\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/stakeup.be\/nl\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/stakeup.be\/nl\/wp-json\/wp\/v2\/posts?categories=1136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}