{"id":1137,"count":0,"description":"","link":"https:\/\/stakeup.be\/nl\/category\/geavanceerde-technieken\/","name":"Geavanceerde technieken","slug":"geavanceerde-technieken","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/stakeup.be\/nl\/wp-json\/wp\/v2\/categories\/1137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stakeup.be\/nl\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/stakeup.be\/nl\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/stakeup.be\/nl\/wp-json\/wp\/v2\/posts?categories=1137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}